{"id":23186,"date":"2023-07-26T10:44:34","date_gmt":"2023-07-26T10:44:34","guid":{"rendered":"https:\/\/stopcarcinogensatwork.eu\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/"},"modified":"2025-09-04T11:31:40","modified_gmt":"2025-09-04T11:31:40","slug":"extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung","status":"publish","type":"good-practice","link":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/","title":{"rendered":"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung"},"content":{"rendered":"<p>Chroms\u00e4ure wurde 2013 in die REACH-Zulassungsliste aufgenommen und ihre Verwendung ist seit 2017 in der EU zulassungspflichtig.<\/p>\n<p>Die extreme Hochgeschwindigkeits-Lasermaterialabscheidung (EHLA) kann eine technische Alternative zur Hartverchromung bieten, die sich besonders f\u00fcr rotationssymmetrische Bauteile eignet.<\/p>\n<p>Das Verfahren bietet eine Alternative f\u00fcr Anwendungen, bei denen erh\u00f6hte Anforderungen gestellt werden, z.B. an die Haftung der Beschichtung sowie die Verhinderung von Korrosion der beschichteten Oberfl\u00e4che und den Schutz vor Verschlei\u00df des behandelten Metalls.<\/p>\n","protected":false},"template":"","sector":[],"carcinogens":[301],"stop":[302],"country":[1439],"class_list":["post-23186","good-practice","type-good-practice","status-publish","hentry","carcinogens-chrom","stop-substitutionsmasnahme","country-deutschland"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung<\/title>\n<meta name=\"description\" content=\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung\" \/>\n<meta property=\"og:description\" content=\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/\" \/>\n<meta property=\"og:site_name\" content=\"STOP carcinogens at work\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T11:31:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\\\/\",\"name\":\"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#website\"},\"datePublished\":\"2023-07-26T10:44:34+00:00\",\"dateModified\":\"2025-09-04T11:31:40+00:00\",\"description\":\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Good practice\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alle krebserzeugenden Stoffe\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/carcinogens\\\/alle-krebserzeugenden-stoffe\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Chrom\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/carcinogens\\\/chrom\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/\",\"name\":\"STOP Carcinogens at work\",\"description\":\"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#organization\"},\"alternateName\":\"Roadmap on Carcinogens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#organization\",\"name\":\"TNO\",\"alternateName\":\"This is a European wide voluntary action scheme\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"contentUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"width\":512,\"height\":512,\"caption\":\"TNO\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"publishingPrinciples\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/homepage\\\/legal\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/general\\\/about-us\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung","description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/","og_locale":"de_DE","og_type":"article","og_title":"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung","og_description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","og_url":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/","og_site_name":"STOP carcinogens at work","article_modified_time":"2025-09-04T11:31:40+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/","url":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/","name":"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung","isPartOf":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#website"},"datePublished":"2023-07-26T10:44:34+00:00","dateModified":"2025-09-04T11:31:40+00:00","description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","breadcrumb":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/extreme-high-speed-laser-material-deposition-ehla-als-technische-alternative-fuer-bestimmte-anwendungen-zur-hartverchromung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopcarcinogensatwork.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Good practice","item":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/"},{"@type":"ListItem","position":3,"name":"Alle krebserzeugenden Stoffe","item":"https:\/\/stopcarcinogensatwork.eu\/de\/carcinogens\/alle-krebserzeugenden-stoffe\/"},{"@type":"ListItem","position":4,"name":"Chrom","item":"https:\/\/stopcarcinogensatwork.eu\/de\/carcinogens\/chrom\/"},{"@type":"ListItem","position":5,"name":"Extreme High-Speed Laser Material Deposition (EHLA) als technische Alternative f\u00fcr bestimmte Anwendungen zur Hartverchromung"}]},{"@type":"WebSite","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#website","url":"https:\/\/stopcarcinogensatwork.eu\/de\/","name":"STOP Carcinogens at work","description":"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.","publisher":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#organization"},"alternateName":"Roadmap on Carcinogens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopcarcinogensatwork.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#organization","name":"TNO","alternateName":"This is a European wide voluntary action scheme","url":"https:\/\/stopcarcinogensatwork.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","contentUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","width":512,"height":512,"caption":"TNO"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/stopcarcinogensatwork.eu\/homepage\/legal\/","ownershipFundingInfo":"https:\/\/stopcarcinogensatwork.eu\/general\/about-us\/"}]}},"_links":{"self":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/good-practice\/23186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/good-practice"}],"about":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/types\/good-practice"}],"wp:attachment":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/media?parent=23186"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/sector?post=23186"},{"taxonomy":"carcinogens","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/carcinogens?post=23186"},{"taxonomy":"stop","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/stop?post=23186"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/country?post=23186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}