{"id":40857,"date":"2017-12-13T09:43:21","date_gmt":"2017-12-13T09:43:21","guid":{"rendered":"https:\/\/stopcarcinogensatwork.eu\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/"},"modified":"2025-09-04T11:21:06","modified_gmt":"2025-09-04T11:21:06","slug":"schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft","status":"publish","type":"good-practice","link":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/","title":{"rendered":"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft"},"content":{"rendered":"<h2>Schauplatz und Problem<\/h2>\n<p>Die Landwirtschaft in Europa steht vor wachsenden Herausforderungen und Problemen. Einige davon k\u00f6nnen nicht kontrolliert werden, wie die Weltwirtschaft, Wetterextreme und der Klimawandel. Aber die Landwirte k\u00f6nnen die Frage der Gesundheit und Sicherheit kontrollieren, zum Beispiel bei der Arbeit mit gef\u00e4hrlichen Stoffen. Gef\u00e4hrliche Stoffe kommen in der Landwirtschaft und Forstwirtschaft in vielen Formen vor. Zum Beispiel: Pestizide, Kraftstoffe und Chemikalien, aber auch G\u00fclle und Tierfl\u00fcssigkeiten. Diese Gefahrstoffe k\u00f6nnen Vergiftungen, Magenbeschwerden, Krebs, chronische Krankheiten und Tod verursachen.     <\/p>\n<h2>L\u00f6sung<\/h2>\n<p>Es ist nicht m\u00f6glich, alle gef\u00e4hrlichen Stoffe aus der Landwirtschaft in Europa zu verbannen. Aber es ist wichtig, dass Landwirte wissen, wie sie mit gef\u00e4hrlichen Stoffen umgehen und was sie tun und lassen sollten. Aus diesem Grund hat die Europ\u00e4ische Kommission einen Leitfaden mit dem Titel: &#8222;Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft&#8220;. Dieser Leitfaden enth\u00e4lt Hintergrundinformationen zu Gesundheit und Sicherheit und ein Kapitel speziell zu Gefahrstoffen.   <\/p>\n<h2>Ergebnisse<\/h2>\n<p>Der Leitfaden informiert die Landwirte dar\u00fcber, dass sie bei der Verwendung gef\u00e4hrlicher Stoffe Folgendes beachten sollten:<\/p>\n<ul>\n<li>Stellen Sie sicher, dass sie von den zust\u00e4ndigen nationalen Beh\u00f6rden zugelassen sind;<\/li>\n<li>Lesen Sie das Etikett und befolgen Sie die Anweisungen des Herstellers;<\/li>\n<li>Verwenden Sie eine saubere pers\u00f6nliche Schutzausr\u00fcstung;<\/li>\n<li>Nicht mit anderen gef\u00e4hrlichen Stoffen mischen;<\/li>\n<li>Spr\u00fchen Sie nicht bei Wind oder gegen den Wind<\/li>\n<li>Lassen Sie L\u00f6sungen nicht unbeschriftet oder unbeaufsichtigt.<\/li>\n<\/ul>\n<p>Wenn Sie diese Regeln befolgen, k\u00f6nnen Sie die Risiken bei der Arbeit mit Gefahrstoffen verringern.<\/p>\n<p>Der Leitfaden ist in 22 der offiziellen Sprachen verf\u00fcgbar.<\/p>\n","protected":false},"template":"","sector":[1241],"carcinogens":[1017,1138],"stop":[300,296],"country":[1443],"class_list":["post-40857","good-practice","type-good-practice","status-publish","hentry","sector-landwirtschaft-de","carcinogens-dieselmotoremissionen-dee","carcinogens-pestizide","stop-organisatorische-masnahme","stop-technische-masnahme","country-europa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft<\/title>\n<meta name=\"description\" content=\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft\" \/>\n<meta property=\"og:description\" content=\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"STOP carcinogens at work\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T11:21:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\\\/\",\"name\":\"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#website\"},\"datePublished\":\"2017-12-13T09:43:21+00:00\",\"dateModified\":\"2025-09-04T11:21:06+00:00\",\"description\":\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Good practice\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/good-practice\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alle krebserzeugenden Stoffe\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/carcinogens\\\/alle-krebserzeugenden-stoffe\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dieselmotoremissionen (DME)\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/carcinogens\\\/dieselmotoremissionen-dee\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/\",\"name\":\"STOP Carcinogens at work\",\"description\":\"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#organization\"},\"alternateName\":\"Roadmap on Carcinogens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#organization\",\"name\":\"TNO\",\"alternateName\":\"This is a European wide voluntary action scheme\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"contentUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"width\":512,\"height\":512,\"caption\":\"TNO\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"publishingPrinciples\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/homepage\\\/legal\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/general\\\/about-us\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft","description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft","og_description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","og_url":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/","og_site_name":"STOP carcinogens at work","article_modified_time":"2025-09-04T11:21:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/","url":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/","name":"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft","isPartOf":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#website"},"datePublished":"2017-12-13T09:43:21+00:00","dateModified":"2025-09-04T11:21:06+00:00","description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","breadcrumb":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/schutz-der-gesundheit-und-sicherheit-von-arbeitnehmern-in-landwirtschaft-viehzucht-gartenbau-und-forstwirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopcarcinogensatwork.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Good practice","item":"https:\/\/stopcarcinogensatwork.eu\/de\/good-practice\/"},{"@type":"ListItem","position":3,"name":"Alle krebserzeugenden Stoffe","item":"https:\/\/stopcarcinogensatwork.eu\/de\/carcinogens\/alle-krebserzeugenden-stoffe\/"},{"@type":"ListItem","position":4,"name":"Dieselmotoremissionen (DME)","item":"https:\/\/stopcarcinogensatwork.eu\/de\/carcinogens\/dieselmotoremissionen-dee\/"},{"@type":"ListItem","position":5,"name":"Schutz von Gesundheit und Sicherheit der Besch\u00e4ftigten in Landwirtschaft, Viehzucht, Gartenbau und Forstwirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#website","url":"https:\/\/stopcarcinogensatwork.eu\/de\/","name":"STOP Carcinogens at work","description":"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.","publisher":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#organization"},"alternateName":"Roadmap on Carcinogens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopcarcinogensatwork.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#organization","name":"TNO","alternateName":"This is a European wide voluntary action scheme","url":"https:\/\/stopcarcinogensatwork.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","contentUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","width":512,"height":512,"caption":"TNO"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/de\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/stopcarcinogensatwork.eu\/homepage\/legal\/","ownershipFundingInfo":"https:\/\/stopcarcinogensatwork.eu\/general\/about-us\/"}]}},"_links":{"self":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/good-practice\/40857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/good-practice"}],"about":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/types\/good-practice"}],"wp:attachment":[{"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/media?parent=40857"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/sector?post=40857"},{"taxonomy":"carcinogens","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/carcinogens?post=40857"},{"taxonomy":"stop","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/stop?post=40857"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/de\/wp-json\/wp\/v2\/country?post=40857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}