{"id":44734,"date":"2023-07-26T12:13:38","date_gmt":"2023-07-26T12:13:38","guid":{"rendered":"https:\/\/stopcarcinogensatwork.eu\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/"},"modified":"2025-09-04T11:06:25","modified_gmt":"2025-09-04T11:06:25","slug":"eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia","status":"publish","type":"good-practice","link":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/","title":{"rendered":"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda"},"content":{"rendered":"<p>Una lavander\u00eda hospitalaria situada en Madrid limpiaba en seco s\u00e1banas, toallas, ropa de trabajo, etc. para varios centros sanitarios. El percloroetileno (tambi\u00e9n conocido como tetracloroetano) se utilizaba s\u00f3lo para eliminar manchas persistentes. <\/p>\n<p>Una intervenci\u00f3n de la Uni\u00f3n consigui\u00f3 eliminar el producto nocivo percloroetileno, y ahora se desecha la ropa con manchas persistentes.<\/p>\n","protected":false},"template":"","sector":[2222],"carcinogens":[1631],"stop":[2061],"country":[2276],"class_list":["post-44734","good-practice","type-good-practice","status-publish","hentry","sector-actividades-sanitarias-y-de-servicios-sociales","carcinogens-tricloroetileno-es","stop-sustitucion","country-espana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda<\/title>\n<meta name=\"description\" content=\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda\" \/>\n<meta property=\"og:description\" content=\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/\" \/>\n<meta property=\"og:site_name\" content=\"STOP carcinogens at work\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T11:06:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/good-practice\\\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/good-practice\\\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\\\/\",\"name\":\"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/#website\"},\"datePublished\":\"2023-07-26T12:13:38+00:00\",\"dateModified\":\"2025-09-04T11:06:25+00:00\",\"description\":\"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/good-practice\\\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/good-practice\\\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/good-practice\\\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Good practice\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/good-practice\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Todos los carcin\u00f3genos\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/carcinogens\\\/todos-los-carcinogenos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tricloroetileno\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/carcinogens\\\/tricloroetileno-es\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/\",\"name\":\"STOP Carcinogens at work\",\"description\":\"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/#organization\"},\"alternateName\":\"Roadmap on Carcinogens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/#organization\",\"name\":\"TNO\",\"alternateName\":\"This is a European wide voluntary action scheme\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"contentUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"width\":512,\"height\":512,\"caption\":\"TNO\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"publishingPrinciples\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/homepage\\\/legal\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/general\\\/about-us\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda","description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/","og_locale":"es_ES","og_type":"article","og_title":"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda","og_description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","og_url":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/","og_site_name":"STOP carcinogens at work","article_modified_time":"2025-09-04T11:06:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/","url":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/","name":"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda","isPartOf":{"@id":"https:\/\/stopcarcinogensatwork.eu\/es\/#website"},"datePublished":"2023-07-26T12:13:38+00:00","dateModified":"2025-09-04T11:06:25+00:00","description":"Many other companies are taking measures to completely avoid or protect workers from exposure to carcinogenic substances.","breadcrumb":{"@id":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/eliminacion-del-percloroetileno-utilizado-para-la-limpieza-en-seco-en-una-lavanderia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopcarcinogensatwork.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Good practice","item":"https:\/\/stopcarcinogensatwork.eu\/es\/good-practice\/"},{"@type":"ListItem","position":3,"name":"Todos los carcin\u00f3genos","item":"https:\/\/stopcarcinogensatwork.eu\/es\/carcinogens\/todos-los-carcinogenos\/"},{"@type":"ListItem","position":4,"name":"Tricloroetileno","item":"https:\/\/stopcarcinogensatwork.eu\/es\/carcinogens\/tricloroetileno-es\/"},{"@type":"ListItem","position":5,"name":"Eliminaci\u00f3n del percloroetileno utilizado para la limpieza en seco en una lavander\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/stopcarcinogensatwork.eu\/es\/#website","url":"https:\/\/stopcarcinogensatwork.eu\/es\/","name":"STOP Carcinogens at work","description":"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.","publisher":{"@id":"https:\/\/stopcarcinogensatwork.eu\/es\/#organization"},"alternateName":"Roadmap on Carcinogens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopcarcinogensatwork.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/stopcarcinogensatwork.eu\/es\/#organization","name":"TNO","alternateName":"This is a European wide voluntary action scheme","url":"https:\/\/stopcarcinogensatwork.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stopcarcinogensatwork.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","contentUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","width":512,"height":512,"caption":"TNO"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/es\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/stopcarcinogensatwork.eu\/homepage\/legal\/","ownershipFundingInfo":"https:\/\/stopcarcinogensatwork.eu\/general\/about-us\/"}]}},"_links":{"self":[{"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/good-practice\/44734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/good-practice"}],"about":[{"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/types\/good-practice"}],"wp:attachment":[{"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/media?parent=44734"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/sector?post=44734"},{"taxonomy":"carcinogens","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/carcinogens?post=44734"},{"taxonomy":"stop","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/stop?post=44734"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/es\/wp-json\/wp\/v2\/country?post=44734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}