{"id":39832,"date":"2023-08-29T10:09:24","date_gmt":"2023-08-29T10:09:24","guid":{"rendered":"https:\/\/stopcarcinogensatwork.eu\/fact\/14-dioxane\/"},"modified":"2026-06-13T11:28:40","modified_gmt":"2026-06-13T11:28:40","slug":"14-dioxane","status":"publish","type":"fact","link":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/","title":{"rendered":"1,4-Dioxane"},"content":{"rendered":"<blockquote><p>On estime que jusqu\u2019\u00e0 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane dans l\u2019Union europ\u00e9enne. Les lieux de travail typiques o\u00f9 le 1,4-Dioxane est utilis\u00e9 se trouvent dans l\u2019industrie du caoutchouc et l\u2019industrie chimique. Il peut \u00e9galement appara\u00eetre comme sous-produit dans l\u2019industrie cosm\u00e9tique. Les travailleurs y sont principalement expos\u00e9s par contamination atmosph\u00e9rique et par contact cutan\u00e9, bien qu\u2019une exposition par voie orale soit \u00e9galement possible. Le 1,4-Dioxane est class\u00e9 comme substance canc\u00e9rog\u00e8ne de cat\u00e9gorie 1B selon la l\u00e9gislation CLP (Carc. 1B) et est soup\u00e7onn\u00e9 de contribuer \u00e0 l&rsquo;apparition de carcinomes nasaux ainsi que de tumeurs du foie et des reins. De plus, le 1,4-Dioxane provoque une irritation oculaire grave et peut provoquer une irritation respiratoire ; une exposition r\u00e9p\u00e9t\u00e9e de la peau peut entra\u00eener une s\u00e9cheresse ou des ger\u00e7ures.     <\/p><\/blockquote>\n<h2>O\u00f9 se situent les risques ?<\/h2>\n<p>L&rsquo;exposition professionnelle se produit lors de la production, du traitement et de l&rsquo;utilisation du 1,4-Dioxane, par inhalation ou par voie cutan\u00e9e. Le 1,4-Dioxane est souvent utilis\u00e9 comme solvant, dans les laboratoires (par exemple, phase mobile en chromatographie) et sur les sites industriels dans les processus de polym\u00e9risation. Les activit\u00e9s de nettoyage et d&rsquo;entretien sont \u00e9galement importantes \u00e0 prendre en compte en ce qui concerne l&rsquo;exposition.  <\/p>\n<h2>En savoir plus sur la substance<\/h2>\n<p>Le 1,4-Dioxane est un liquide clair et incolore, qui se m\u00e9lange facilement \u00e0 d&rsquo;autres solvants. En raison de son inertie, il est principalement utilis\u00e9 comme solvant. Il est hautement inflammable et peut former des peroxydes explosifs. Le 1,4-Dioxane est un produit chimique anthropique qui n&rsquo;existe pas \u00e0 l \u00ab \u00e9tat naturel dans l&rsquo;environnement. C&rsquo;est un sous-produit connu des processus industriels d \u00bb \u00e9thoxylation et il peut donc \u00eatre pr\u00e9sent en tant que contaminant dans les cosm\u00e9tiques et les produits de soins personnels, o\u00f9 sa concentration est strictement r\u00e9glement\u00e9e. Le 1,4-Dioxane a \u00e9galement \u00e9t\u00e9 trouv\u00e9 comme r\u00e9sidu dans des articles en plastique et en caoutchouc (par exemple, gants, bottes, v\u00eatements, poign\u00e9es en caoutchouc, levier de vitesse, volants).     <\/p>\n<p>Le 1,4-Dioxane est stable dans l&rsquo;eau et ne se d\u00e9compose pas. Les compos\u00e9s pr\u00e9sents dans l&rsquo;air peuvent d\u00e9composer rapidement le 1,4-Dioxane en diff\u00e9rents compos\u00e9s. La contamination de l&rsquo;environnement (eaux souterraines) est li\u00e9e \u00e0 l \u00ab \u00e9limination de solvants chimiques contenant du 1,4-Dioxane et \u00e0 l \u00bb \u00e9limination du 1,4-Dioxane lui-m\u00eame.  <\/p>\n<h2>Dangers pouvant survenir<\/h2>\n<p>Le 1,4-Dioxane est rapidement et presque compl\u00e8tement absorb\u00e9 apr\u00e8s inhalation et exposition orale. L&rsquo;absorption par la peau est \u00e9galement importante. L&rsquo;inhalation de 1,4-Dioxane peut provoquer des douleurs dans la partie sup\u00e9rieure de l&rsquo;abdomen et des vomissements, ainsi qu&rsquo;une irritation des yeux et des voies respiratoires. D&rsquo;autres sympt\u00f4mes de l&rsquo;intoxication au 1,4-Dioxane comprennent des l\u00e9sions h\u00e9patiques et r\u00e9nales, des convulsions et le coma. Dans ce contexte, il convient de tenir compte de l&rsquo;absorption simultan\u00e9e de la substance par voie cutan\u00e9e. En outre, une exposition cutan\u00e9e r\u00e9p\u00e9t\u00e9e au 1,4-Dioxane peut entra\u00eener des l\u00e9sions cutan\u00e9es. En outre, des \u00e9tudes animales ont mis en \u00e9vidence des effets sur le foie et les reins ainsi que sur le syst\u00e8me nerveux central, tels qu&rsquo;une d\u00e9marche chancelante, une narcose, une paralysie et un coma. Il convient de noter que les principaux organes cibles sont le syst\u00e8me respiratoire, le foie et les reins apr\u00e8s une exposition \u00e0 long terme.       <\/p>\n<h2>Ce que vous pouvez faire<\/h2>\n<p>Il convient d&rsquo;envisager la substitution dans les applications o\u00f9 cela est possible. Si aucune alternative n&rsquo;est disponible ou si du 1,4-Dioxane risque d&rsquo;\u00eatre produit en tant que sous-produit, effectuez r\u00e9guli\u00e8rement des mesures d&rsquo;exposition appropri\u00e9es afin de d\u00e9terminer quand et o\u00f9 des mesures doivent \u00eatre prises. Pour \u00e9viter tout effet n\u00e9faste sur la sant\u00e9, il est donc primordial de r\u00e9duire l&rsquo;exposition en dessous de la valeur limite fix\u00e9e sur la base de crit\u00e8res sanitaires. Dans les proc\u00e9d\u00e9s industriels, les syst\u00e8mes ferm\u00e9s, la ventilation g\u00e9n\u00e9rale et la ventilation locale constituent des exemples de mesures de contr\u00f4le techniques. M\u00eame lorsque l&rsquo;on travaille avec des syst\u00e8mes ferm\u00e9s, une exposition peut se produire, par exemple lors de t\u00e2ches d&rsquo;\u00e9chantillonnage. Des mesures et des mesures de contr\u00f4le sont alors pertinentes. D&rsquo;autres pratiques de travail recommand\u00e9es comprennent la fourniture d&rsquo;informations sur les dangers et la formation des employ\u00e9s, ainsi que des normes g\u00e9n\u00e9rales d&rsquo;hygi\u00e8ne de travail pour les zones de manipulation de produits chimiques. Les travailleurs charg\u00e9s de la maintenance et du nettoyage doivent \u00e9galement \u00eatre form\u00e9s. V\u00e9rifiez si les travailleurs signalent des sympt\u00f4mes pr\u00e9coces. Il est recommand\u00e9 de faire appel \u00e0 un m\u00e9decin du travail. Sachez que pour le 1,4-Dioxane, l\u2019\u00e9valuation de l\u2019exposition peut \u00eatre compl\u00e9t\u00e9e par une biosurveillance, si la l\u00e9gislation nationale le permet. Les travailleurs doivent \u00eatre inform\u00e9s des effets de l\u2019exposition. Les \u00e9quipements de protection individuelle ne doivent \u00eatre utilis\u00e9s qu\u2019en dernier recours, apr\u00e8s avoir mis en place les solutions techniques possibles.              <\/p>\n<p><em>Sources : BAuA, CLP, Commission allemande MAK, RAC<\/em><\/p>\n","protected":false},"template":"","carcinogens":[1520],"class_list":["post-39832","fact","type-fact","status-publish","hentry","carcinogens-14-dioxane-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1,4-Dioxane - STOP carcinogens at work<\/title>\n<meta name=\"description\" content=\"Dans l&#039;Union europ\u00e9enne, 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane. Cette substance est soup\u00e7onn\u00e9e d&#039;\u00eatre \u00e0 l&#039;origine de carcinomes nasaux ainsi que de tumeurs du foie et des reins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1,4-Dioxane\" \/>\n<meta property=\"og:description\" content=\"Dans l&#039;Union europ\u00e9enne, 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane. Cette substance est soup\u00e7onn\u00e9e d&#039;\u00eatre \u00e0 l&#039;origine de carcinomes nasaux ainsi que de tumeurs du foie et des reins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/\" \/>\n<meta property=\"og:site_name\" content=\"STOP carcinogens at work\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-13T11:28:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/fact\\\/14-dioxane\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/fact\\\/14-dioxane\\\/\",\"name\":\"1,4-Dioxane - STOP carcinogens at work\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#website\"},\"datePublished\":\"2023-08-29T10:09:24+00:00\",\"dateModified\":\"2026-06-13T11:28:40+00:00\",\"description\":\"Dans l'Union europ\u00e9enne, 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane. Cette substance est soup\u00e7onn\u00e9e d'\u00eatre \u00e0 l'origine de carcinomes nasaux ainsi que de tumeurs du foie et des reins.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/fact\\\/14-dioxane\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/fact\\\/14-dioxane\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/fact\\\/14-dioxane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facts\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/fact\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tous les canc\u00e9rog\u00e8nes\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/carcinogens\\\/tous-les-carinogenes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"1,4-Dioxane\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/carcinogens\\\/14-dioxane-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"1,4-Dioxane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/\",\"name\":\"STOP Carcinogens at work\",\"description\":\"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Roadmap on Carcinogens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#organization\",\"name\":\"TNO\",\"alternateName\":\"This is a European wide voluntary action scheme\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"contentUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"width\":512,\"height\":512,\"caption\":\"TNO\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"publishingPrinciples\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/homepage\\\/legal\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/general\\\/about-us\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1,4-Dioxane - STOP carcinogens at work","description":"Dans l'Union europ\u00e9enne, 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane. Cette substance est soup\u00e7onn\u00e9e d'\u00eatre \u00e0 l'origine de carcinomes nasaux ainsi que de tumeurs du foie et des reins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/","og_locale":"fr_FR","og_type":"article","og_title":"1,4-Dioxane","og_description":"Dans l'Union europ\u00e9enne, 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane. Cette substance est soup\u00e7onn\u00e9e d'\u00eatre \u00e0 l'origine de carcinomes nasaux ainsi que de tumeurs du foie et des reins.","og_url":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/","og_site_name":"STOP carcinogens at work","article_modified_time":"2026-06-13T11:28:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/","url":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/","name":"1,4-Dioxane - STOP carcinogens at work","isPartOf":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#website"},"datePublished":"2023-08-29T10:09:24+00:00","dateModified":"2026-06-13T11:28:40+00:00","description":"Dans l'Union europ\u00e9enne, 30 000 travailleurs sont expos\u00e9s au 1,4-Dioxane. Cette substance est soup\u00e7onn\u00e9e d'\u00eatre \u00e0 l'origine de carcinomes nasaux ainsi que de tumeurs du foie et des reins.","breadcrumb":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/14-dioxane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopcarcinogensatwork.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Facts","item":"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/"},{"@type":"ListItem","position":3,"name":"Tous les canc\u00e9rog\u00e8nes","item":"https:\/\/stopcarcinogensatwork.eu\/fr\/carcinogens\/tous-les-carinogenes\/"},{"@type":"ListItem","position":4,"name":"1,4-Dioxane","item":"https:\/\/stopcarcinogensatwork.eu\/fr\/carcinogens\/14-dioxane-fr\/"},{"@type":"ListItem","position":5,"name":"1,4-Dioxane"}]},{"@type":"WebSite","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#website","url":"https:\/\/stopcarcinogensatwork.eu\/fr\/","name":"STOP Carcinogens at work","description":"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.","publisher":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#organization"},"alternateName":"Roadmap on Carcinogens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopcarcinogensatwork.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#organization","name":"TNO","alternateName":"This is a European wide voluntary action scheme","url":"https:\/\/stopcarcinogensatwork.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","contentUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","width":512,"height":512,"caption":"TNO"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/stopcarcinogensatwork.eu\/homepage\/legal\/","ownershipFundingInfo":"https:\/\/stopcarcinogensatwork.eu\/general\/about-us\/"}]}},"_links":{"self":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/fact\/39832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/fact"}],"about":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/types\/fact"}],"wp:attachment":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/media?parent=39832"}],"wp:term":[{"taxonomy":"carcinogens","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/carcinogens?post=39832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}