{"id":100301,"date":"2026-04-20T09:18:42","date_gmt":"2026-04-20T09:18:42","guid":{"rendered":"https:\/\/stopcarcinogensatwork.eu\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/"},"modified":"2026-04-20T09:18:42","modified_gmt":"2026-04-20T09:18:42","slug":"industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail","status":"publish","type":"post","link":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/","title":{"rendered":"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?"},"content":{"rendered":"<p><strong>Les mat\u00e9riaux couramment manipul\u00e9s dans les usines chimiques, y compris divers produits chimiques, solvants et sous-produits de r\u00e9action, peuvent contenir des substances dangereuses qui pr\u00e9sentent un risque de dommages potentiels.<\/strong> <strong>En tant que professionnel dans ce domaine, il est essentiel d&rsquo;\u00eatre conscient des risques professionnels potentiels associ\u00e9s \u00e0 votre r\u00f4le, y compris un risque \u00e9lev\u00e9 de d\u00e9velopper des conditions telles que des probl\u00e8mes respiratoires, des troubles cutan\u00e9s ou une susceptibilit\u00e9 accrue \u00e0 certains cancers.<\/strong><\/p>\n<p>Ces substances, telles que des produits chimiques corrosifs, des compos\u00e9s toxiques et des canc\u00e9rog\u00e8nes potentiels, peuvent pr\u00e9senter des risques pour la sant\u00e9 en cas d&rsquo;inhalation, de contact avec la peau ou d&rsquo;ingestion. Le risque est r\u00e9el. La bonne nouvelle ? La connaissance est le premier pas vers la protection.   <\/p>\n<p>C&rsquo;est pr\u00e9cis\u00e9ment la raison pour laquelle nous proposons plus de 40 fiches d&rsquo;information sur les substances canc\u00e9rig\u00e8nes au travail. De l&rsquo;<a href=\"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/acrylonitrile\/\">Acrylonitrile<\/a> \u00e0 l&rsquo;<a href=\"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/isoprene\/\">Isopr\u00e8ne<\/a> en passant par le <a href=\"https:\/\/stopcarcinogensatwork.eu\/fr\/fact\/rayonnement-ultraviolet\/\">rayonnement ultraviolet<\/a>, chaque fiche vous donne des informations claires et fiables sur ce qu&rsquo;est une substance, o\u00f9 on la trouve, combien de travailleurs y sont expos\u00e9s, quels sont les risques pour la sant\u00e9 et ce que l&rsquo;on peut faire pour r\u00e9duire ou \u00e9liminer l&rsquo;exposition. <\/p>\n<h2><strong>Les substances sont partout autour de nous<\/strong><\/h2>\n<p>Certains canc\u00e9rog\u00e8nes sont bien connus. L&rsquo;Amiante, par exemple, affecte encore aujourd&rsquo;hui des millions d&rsquo;Ouvriers de l&rsquo;UE, en particulier dans les secteurs de la construction et de la r\u00e9novation. D&rsquo;autres sont moins \u00e9vidents. Le Formald\u00e9hyde est pr\u00e9sent dans la colle, le contreplaqu\u00e9 et m\u00eame les conteneurs d&rsquo;exp\u00e9dition. La poussi\u00e8re de bois est \u00e0 l&rsquo;origine d&rsquo;une exposition de haut niveau pour une part importante des travailleurs du bois. La vari\u00e9t\u00e9 des substances, des secteurs et des situations est \u00e9norme. C&rsquo;est pourquoi une approche unique ne fonctionne tout simplement pas.      <\/p>\n<h2><strong>Trouvez les faits correspondant \u00e0 votre situation<\/strong><\/h2>\n<p>Nos fiches sont con\u00e7ues pour \u00eatre pratiques et faciles \u00e0 utiliser pour les travailleurs, les employeurs, les repr\u00e9sentants de la s\u00e9curit\u00e9 et les inspecteurs. Chacune d&rsquo;entre elles aborde les faits essentiels sans jargon inutile, en se concentrant directement sur ce qui compte : comprendre le risque et prendre des mesures. <\/p>\n<p>Vous travaillez avec des produits chimiques ? Vous conduisez ou entretenez des v\u00e9hicules \u00e9quip\u00e9s de moteurs diesel ? Vous travaillez \u00e0 l&rsquo;ext\u00e9rieur, dans le secteur des soins de sant\u00e9 ou avec des mat\u00e9riaux de construction ? Il existe une fiche d&rsquo;information pour vous.   <\/p>\n<p>N&rsquo;attendez pas que le mal soit fait. Consultez notre <a href=\"https:\/\/stopcarcinogensatwork.eu\/fr\/recherche-de-faits\/\">page de fiches d&rsquo;information<\/a> et d\u00e9couvrez ce \u00e0 quoi vous ou vos coll\u00e8gues pourriez \u00eatre expos\u00e9s et ce que vous pouvez faire d\u00e8s aujourd&rsquo;hui. <\/p>\n<p><strong>Les cancers professionnels sont en grande partie \u00e9vitables. Mais seulement si nous agissons maintenant. <\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-100286\" src=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg\" alt=\"\" width=\"294\" height=\"294\" srcset=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg 720w, https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1-300x300.jpeg 300w, https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1-150x150.jpeg 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/> <img decoding=\"async\" class=\"alignnone wp-image-100287\" src=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide2.jpeg\" alt=\"\" width=\"295\" height=\"295\" srcset=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide2.jpeg 720w, https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide2-300x300.jpeg 300w, https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide2-150x150.jpeg 150w\" sizes=\"(max-width: 295px) 100vw, 295px\" \/> <img decoding=\"async\" class=\"alignnone wp-image-100288\" src=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide3.jpeg\" alt=\"\" width=\"295\" height=\"295\" srcset=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide3.jpeg 720w, https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide3-300x300.jpeg 300w, https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide3-150x150.jpeg 150w\" sizes=\"(max-width: 295px) 100vw, 295px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les mat\u00e9riaux couramment manipul\u00e9s dans les usines chimiques, y compris divers produits chimiques, solvants et sous-produits de r\u00e9action, peuvent contenir des substances dangereuses qui pr\u00e9sentent un risque de dommages potentiels. En tant que professionnel dans ce domaine, il est essentiel d&rsquo;\u00eatre conscient des risques professionnels potentiels associ\u00e9s \u00e0 votre r\u00f4le, y compris un risque \u00e9lev\u00e9 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[],"carcinogens":[],"country":[],"class_list":["post-100301","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ? - STOP carcinogens at work<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?\" \/>\n<meta property=\"og:description\" content=\"Les mat\u00e9riaux couramment manipul\u00e9s dans les usines chimiques, y compris divers produits chimiques, solvants et sous-produits de r\u00e9action, peuvent contenir des substances dangereuses qui pr\u00e9sentent un risque de dommages potentiels. En tant que professionnel dans ce domaine, il est essentiel d&rsquo;\u00eatre conscient des risques professionnels potentiels associ\u00e9s \u00e0 votre r\u00f4le, y compris un risque \u00e9lev\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/\" \/>\n<meta property=\"og:site_name\" content=\"STOP carcinogens at work\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T09:18:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EJ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"EJ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/\"},\"author\":{\"name\":\"EJ\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#\\\/schema\\\/person\\\/e71281235fb0683570cdd98d0a26b4b5\"},\"headline\":\"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?\",\"datePublished\":\"2026-04-20T09:18:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/\"},\"wordCount\":499,\"publisher\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Slide1.jpeg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/\",\"name\":\"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ? - STOP carcinogens at work\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Slide1.jpeg\",\"datePublished\":\"2026-04-20T09:18:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Slide1.jpeg\",\"contentUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Slide1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/\",\"name\":\"STOP Carcinogens at work\",\"description\":\"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Roadmap on Carcinogens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#organization\",\"name\":\"TNO\",\"alternateName\":\"This is a European wide voluntary action scheme\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"contentUrl\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-FavLarge-1.png\",\"width\":512,\"height\":512,\"caption\":\"TNO\"},\"image\":{\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"publishingPrinciples\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/homepage\\\/legal\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/general\\\/about-us\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stopcarcinogensatwork.eu\\\/fr\\\/#\\\/schema\\\/person\\\/e71281235fb0683570cdd98d0a26b4b5\",\"name\":\"EJ\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ? - STOP carcinogens at work","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/","og_locale":"fr_FR","og_type":"article","og_title":"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?","og_description":"Les mat\u00e9riaux couramment manipul\u00e9s dans les usines chimiques, y compris divers produits chimiques, solvants et sous-produits de r\u00e9action, peuvent contenir des substances dangereuses qui pr\u00e9sentent un risque de dommages potentiels. En tant que professionnel dans ce domaine, il est essentiel d&rsquo;\u00eatre conscient des risques professionnels potentiels associ\u00e9s \u00e0 votre r\u00f4le, y compris un risque \u00e9lev\u00e9 [&hellip;]","og_url":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/","og_site_name":"STOP carcinogens at work","article_published_time":"2026-04-20T09:18:42+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg","type":"image\/jpeg"}],"author":"EJ","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"EJ","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#article","isPartOf":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/"},"author":{"name":"EJ","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#\/schema\/person\/e71281235fb0683570cdd98d0a26b4b5"},"headline":"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?","datePublished":"2026-04-20T09:18:42+00:00","mainEntityOfPage":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/"},"wordCount":499,"publisher":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#organization"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#primaryimage"},"thumbnailUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/","url":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/","name":"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ? - STOP carcinogens at work","isPartOf":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#primaryimage"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#primaryimage"},"thumbnailUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg","datePublished":"2026-04-20T09:18:42+00:00","breadcrumb":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#primaryimage","url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg","contentUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2026\/04\/Slide1.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/industrie-chimique-savez-vous-a-quels-cancerogenes-vous-etes-expose-au-travail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopcarcinogensatwork.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Industrie chimique : savez-vous \u00e0 quels canc\u00e9rog\u00e8nes vous \u00eates expos\u00e9 au travail ?"}]},{"@type":"WebSite","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#website","url":"https:\/\/stopcarcinogensatwork.eu\/fr\/","name":"STOP Carcinogens at work","description":"Every year, about 100.000 people die from cancer that was caused by exposure to carcinogens at work in Europe.","publisher":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#organization"},"alternateName":"Roadmap on Carcinogens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopcarcinogensatwork.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#organization","name":"TNO","alternateName":"This is a European wide voluntary action scheme","url":"https:\/\/stopcarcinogensatwork.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","contentUrl":"https:\/\/stopcarcinogensatwork.eu\/wp-content\/uploads\/2024\/08\/cropped-FavLarge-1.png","width":512,"height":512,"caption":"TNO"},"image":{"@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/stopcarcinogensatwork.eu\/homepage\/legal\/","ownershipFundingInfo":"https:\/\/stopcarcinogensatwork.eu\/general\/about-us\/"},{"@type":"Person","@id":"https:\/\/stopcarcinogensatwork.eu\/fr\/#\/schema\/person\/e71281235fb0683570cdd98d0a26b4b5","name":"EJ"}]}},"_links":{"self":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/posts\/100301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/comments?post=100301"}],"version-history":[{"count":0,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/posts\/100301\/revisions"}],"wp:attachment":[{"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/media?parent=100301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/categories?post=100301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/tags?post=100301"},{"taxonomy":"carcinogens","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/carcinogens?post=100301"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/stopcarcinogensatwork.eu\/fr\/wp-json\/wp\/v2\/country?post=100301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}